{"id":2,"date":"2018-07-11T09:18:18","date_gmt":"2018-07-11T07:18:18","guid":{"rendered":"https:\/\/www.salonesri.it\/2016\/?page_id=2"},"modified":"2018-09-10T17:20:20","modified_gmt":"2018-09-10T15:20:20","slug":"progetto","status":"publish","type":"page","link":"https:\/\/www.salonesri.it\/2016\/","title":{"rendered":"Il progetto"},"content":{"rendered":"<p>Questa \u00e8 una pagina di esempio. Differisce da un articolo del blog perch\u00e9 rimane in posizione fissa e appare nella navigazione del sito (nella maggior parte dei temi). Molte persone iniziano con una pagina informativa che li introduce ai potenziali visitatori. Che potrebbe dire un cosa del genere:<\/p>\n<blockquote><p>Salve! Sono un pony express di giorno, un aspirante attore di notte e questo \u00e8 il mio blog. Vivo a Los Angeles, ho un bellissimo cane di nome Jack e adoro la pi\u00f1a colada. (E trovarmi sotto la pioggia.)<\/p><\/blockquote>\n<p>&#8230;oppure qualche cosa del genere:<\/p>\n<blockquote><p>La XYZ Doohickey Company \u00e8 stata fondata nel 1971 e da allora ha venduto cazzabubbole di qualit\u00e0 ai propri clienti. SI trova a Gotham City, XYZ impiega oltre 2.000 persone e produce le cose pi\u00f9 incredibili per la comunit\u00e0 di Gotham.<\/p><\/blockquote>\n<p>Come nuovo utente WordPress, \u00e8 possibile andare <a href=\"https:\/\/www.salonesri.it\/2016\/wp-admin\/\">sulla bacheca<\/a> per eliminare questa pagina e creare nuove pagine per i propri contenuti. Buon divertimento!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa \u00e8 una pagina di esempio. Differisce da un articolo del blog perch\u00e9 rimane in posizione fissa e appare nella [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salone dell SRI - Edizione 2016<\/title>\n<meta name=\"description\" content=\"Il 18 novembre scorso ETicaNews ha organizzato la prima edizione del Salone dello SRI, iniziativa unica in Italia, rivolta a consulenti e investitori retail. Ebbene, siamo andati a chiedere ai partecipanti cosa si sono portati a casa da quella prima esperienza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salonesri.it\/2016\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salone dell SRI - Edizione 2016\" \/>\n<meta property=\"og:description\" content=\"Il 18 novembre scorso ETicaNews ha organizzato la prima edizione del Salone dello SRI, iniziativa unica in Italia, rivolta a consulenti e investitori retail. Ebbene, siamo andati a chiedere ai partecipanti cosa si sono portati a casa da quella prima esperienza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salonesri.it\/2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Salone SRI 2016\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-10T15:20:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salonesri.it\\\/2016\\\/\",\"url\":\"https:\\\/\\\/www.salonesri.it\\\/2016\\\/\",\"name\":\"Salone dell SRI - Edizione 2016\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salonesri.it\\\/2016\\\/#website\"},\"datePublished\":\"2018-07-11T07:18:18+00:00\",\"dateModified\":\"2018-09-10T15:20:20+00:00\",\"description\":\"Il 18 novembre scorso ETicaNews ha organizzato la prima edizione del Salone dello SRI, iniziativa unica in Italia, rivolta a consulenti e investitori retail. Ebbene, siamo andati a chiedere ai partecipanti cosa si sono portati a casa da quella prima esperienza.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salonesri.it\\\/2016\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salonesri.it\\\/2016\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salonesri.it\\\/2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salonesri.it\\\/2016\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il progetto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salonesri.it\\\/2016\\\/#website\",\"url\":\"https:\\\/\\\/www.salonesri.it\\\/2016\\\/\",\"name\":\"Salone SRI 2016\",\"description\":\"L&#039;unico appuntamento in Italia dedicato al risparmio SRI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salonesri.it\\\/2016\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salone dell SRI - Edizione 2016","description":"Il 18 novembre scorso ETicaNews ha organizzato la prima edizione del Salone dello SRI, iniziativa unica in Italia, rivolta a consulenti e investitori retail. Ebbene, siamo andati a chiedere ai partecipanti cosa si sono portati a casa da quella prima esperienza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salonesri.it\/2016\/","og_locale":"it_IT","og_type":"article","og_title":"Salone dell SRI - Edizione 2016","og_description":"Il 18 novembre scorso ETicaNews ha organizzato la prima edizione del Salone dello SRI, iniziativa unica in Italia, rivolta a consulenti e investitori retail. Ebbene, siamo andati a chiedere ai partecipanti cosa si sono portati a casa da quella prima esperienza.","og_url":"https:\/\/www.salonesri.it\/2016\/","og_site_name":"Salone SRI 2016","article_modified_time":"2018-09-10T15:20:20+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salonesri.it\/2016\/","url":"https:\/\/www.salonesri.it\/2016\/","name":"Salone dell SRI - Edizione 2016","isPartOf":{"@id":"https:\/\/www.salonesri.it\/2016\/#website"},"datePublished":"2018-07-11T07:18:18+00:00","dateModified":"2018-09-10T15:20:20+00:00","description":"Il 18 novembre scorso ETicaNews ha organizzato la prima edizione del Salone dello SRI, iniziativa unica in Italia, rivolta a consulenti e investitori retail. Ebbene, siamo andati a chiedere ai partecipanti cosa si sono portati a casa da quella prima esperienza.","breadcrumb":{"@id":"https:\/\/www.salonesri.it\/2016\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salonesri.it\/2016\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.salonesri.it\/2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salonesri.it\/2016\/"},{"@type":"ListItem","position":2,"name":"Il progetto"}]},{"@type":"WebSite","@id":"https:\/\/www.salonesri.it\/2016\/#website","url":"https:\/\/www.salonesri.it\/2016\/","name":"Salone SRI 2016","description":"L&#039;unico appuntamento in Italia dedicato al risparmio SRI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salonesri.it\/2016\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.salonesri.it\/2016\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salonesri.it\/2016\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.salonesri.it\/2016\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.salonesri.it\/2016\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salonesri.it\/2016\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":3,"href":"https:\/\/www.salonesri.it\/2016\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":276,"href":"https:\/\/www.salonesri.it\/2016\/wp-json\/wp\/v2\/pages\/2\/revisions\/276"}],"wp:attachment":[{"href":"https:\/\/www.salonesri.it\/2016\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}